{"id":264,"date":"2020-09-24T23:55:33","date_gmt":"2020-09-25T05:55:33","guid":{"rendered":"https:\/\/satforce.com.ec\/?page_id=264"},"modified":"2025-10-31T13:35:21","modified_gmt":"2025-10-31T19:35:21","slug":"custodia","status":"publish","type":"page","link":"https:\/\/satforce.com.ec\/index.php\/custodia\/","title":{"rendered":"Custodia"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"264\" data-post-id=\"264\" data-obj-id=\"264\" class=\"elementor elementor-264 dce-elementor-post-264\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ff5073e elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4ff5073e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7834108c\" data-id=\"7834108c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a5ee28 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"39a5ee28\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/satforce.com.ec\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-home\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Custodia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-260033e7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"260033e7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ae0cd82\" data-id=\"6ae0cd82\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c8fad34 elementor-widget elementor-widget-heading\" data-id=\"6c8fad34\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14fd3c59 elementor-widget elementor-widget-heading\" data-id=\"14fd3c59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Terrestre<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc9023 elementor-widget elementor-widget-text-editor\" data-id=\"ffc9023\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div style=\"position: absolute; z-index: 99999999; height: auto; line-height: 1pt; font-size: 1pt;\"><a style=\"color:#ffffff00\" href=\"https:\/\/mostbets.kz\/\">https:\/\/mostbets.kz\/<\/a><a style=\"color:#ffffff00\" href=\"https:\/\/snai-italy.com\/\">snai<\/a><a style=\"color:#ffffff00\" href=\"https:\/\/pin-up-online.com\/\">pin up<\/a><a style=\"color:#ffffff00\" href=\"https:\/\/4ra-bet.com\/\">4rabet bangladesh<\/a><a style=\"color:#ffffff00\" href=\"https:\/\/az-most-bet.com\/\">mosbet<\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b6c0bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b6c0bc\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5ec3bb1f\" data-id=\"5ec3bb1f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bd4eefb elementor-view-framed elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"5bd4eefb\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL29SdDlETzVPQ1AwP2ZlYXR1cmU9b2VtYmVkIn0%3D\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-truck-moving\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b9ceff dce_masking-none elementor-widget elementor-widget-image\" data-id=\"32b9ceff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"971\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador.png 500w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador-154x300.png 154w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador-12x24.png 12w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador-19x36.png 19w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador-25x48.png 25w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d60d43d elementor-widget elementor-widget-spacer\" data-id=\"d60d43d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0fedd elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"c0fedd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f24bc67\" data-id=\"3f24bc67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33957767 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"33957767\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57bec2ef elementor-widget elementor-widget-heading\" data-id=\"57bec2ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA TERRESTRE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cbcf91 elementor-widget elementor-widget-text-editor\" data-id=\"9cbcf91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\tNuestro servicio de custodia terrestre se realiza a trav\u00e9s de una escolta vehicular. Esta escolta garantiza protecci\u00f3n a los bienes resguardados, apoy\u00e1ndose en servicios especializados como <a href=\"https:\/\/diplomarbeit-ghostwriter.com\/\" style=\"color: inherit; text-decoration: none;\">ghostwriter diplomarbeit<\/a>. Por lo tanto, poseemos una flota de camionetas y el personal humano mejor capacitado del pa\u00eds.\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15fa9b93 ha-content--column ha-align--flex-start ha-icon--row elementor-widget elementor-widget-ha-feature-list happy-addon ha-feature-list happy-addon-pro\" data-id=\"15fa9b93\" data-element_type=\"widget\" data-widget_type=\"ha-feature-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <ul class=\"ha-feature-list-wrap\">\n                            <li class=\"ha-list-item\">\n                                            <div class=\"ha-content\">\n                    \n\t\t\t\t\t\t                            <div class=\"ha-icon image\">\n                                <img decoding=\"async\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/custodia-personal.png\" alt=\"Custodia personal\" \/>\n                            <\/div>\n                        \n                        <div class=\"ha-text\">\n                            Custodia personal                        <\/div>\n\n                                        <\/div>\n                                    <\/li>\n                            <li class=\"ha-list-item\">\n                                            <div class=\"ha-content\">\n                    \n\t\t\t\t\t\t                            <div class=\"ha-icon image\">\n                                <img decoding=\"async\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/custodia-cargas.png\" alt=\"Custodia de cargas\" \/>\n                            <\/div>\n                        \n                        <div class=\"ha-text\">\n                            Custodia de cargas                        <\/div>\n\n                                        <\/div>\n                                    <\/li>\n                            <li class=\"ha-list-item\">\n                                            <div class=\"ha-content\">\n                    \n\t\t\t\t\t\t                            <div class=\"ha-icon image\">\n                                <img decoding=\"async\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/candado-satelital.png\" alt=\"Candado satelital\" \/>\n                            <\/div>\n                        \n                        <div class=\"ha-text\">\n                            Candado satelital                        <\/div>\n\n                                        <\/div>\n                                    <\/li>\n                    <\/ul>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4104fde2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4104fde2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b089031\" data-id=\"2b089031\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b7267fe elementor-widget elementor-widget-heading\" data-id=\"7b7267fe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Custodia Personal<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4242e0df elementor-widget elementor-widget-text-editor\" data-id=\"4242e0df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Ofrecemos el servicio de custodia personal a cualquier hora, sea para tr\u00e1mites personales que Involucren objetos de alto valor o dem\u00e1s eventualidades.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78b8cd70\" data-id=\"78b8cd70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dfc628e elementor-widget elementor-widget-spacer\" data-id=\"6dfc628e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d75813 elementor-widget elementor-widget-ha-slider happy-addon ha-slider\" data-id=\"0d75813\" data-element_type=\"widget\" data-settings=\"{&quot;animation_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:3000,&quot;loop&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;arrow&quot;}\" data-widget_type=\"ha-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"hajs-slick ha-slick ha-slick--slider\">\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/1.png\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/2.png\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/3.png\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t<button type=\"button\" class=\"slick-prev\"><i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i><\/button>\n\t\t\n\t\t\t\t\t<button type=\"button\" class=\"slick-next\"><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/button>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-889840c elementor-widget elementor-widget-spacer\" data-id=\"889840c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2ba3cf elementor-widget elementor-widget-spacer\" data-id=\"f2ba3cf\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a29e6fa elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a29e6fa\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76e0e9f\" data-id=\"76e0e9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e6dafe6 elementor-widget elementor-widget-heading\" data-id=\"5e6dafe6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e1163e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1163e3\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41c83776\" data-id=\"41c83776\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-547b4b4a dce_masking-none elementor-widget elementor-widget-image\" data-id=\"547b4b4a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS.png 800w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-300x225.png 300w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-768x576.png 768w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-24x18.png 24w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-36x27.png 36w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-48x36.png 48w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb632ff elementor-widget elementor-widget-heading\" data-id=\"cb632ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DE CARGAS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15eea881 elementor-widget elementor-widget-text-editor\" data-id=\"15eea881\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"page\" title=\"Page 2\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Proporcionamos protecci\u00f3n con nuestras patrullas de custodia armada para el resguardo y seguridad de la carga.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7919e0 elementor-position-right elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"e7919e0\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-satellite-dish\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tCandado satelital\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPor medio de esto podemos (cliente y nosotros) obtener un control permanente del recorrido de su carga (contenedores, furgones, etc.).\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aa43a1c\" data-id=\"aa43a1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22fc65a elementor-widget elementor-widget-ha-slider happy-addon ha-slider\" data-id=\"22fc65a\" data-element_type=\"widget\" data-settings=\"{&quot;animation_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:3000,&quot;loop&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;arrow&quot;}\" data-widget_type=\"ha-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"hajs-slick ha-slick ha-slick--slider\">\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/CUSTODIA-TERRESTRE-470x430-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/custodia_terresetre_4-470x430-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-DRONE-SATELITAL.png\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t<button type=\"button\" class=\"slick-prev\"><i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i><\/button>\n\t\t\n\t\t\t\t\t<button type=\"button\" class=\"slick-next\"><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/button>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c5e6b elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"a8c5e6b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-246d560 elementor-widget elementor-widget-spacer\" data-id=\"246d560\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60009c9 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60009c9\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5da646c\" data-id=\"5da646c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55e84a1 elementor-widget elementor-widget-heading\" data-id=\"55e84a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa85f9f elementor-widget elementor-widget-spacer\" data-id=\"fa85f9f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b245b5c elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b245b5c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e5015e9\" data-id=\"e5015e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b11908c dce_masking-none elementor-widget elementor-widget-image\" data-id=\"b11908c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS.png 800w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-300x225.png 300w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-768x576.png 768w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-24x18.png 24w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-36x27.png 36w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-48x36.png 48w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a7aa58 elementor-widget elementor-widget-heading\" data-id=\"9a7aa58\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DE CARGAS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a62608 elementor-widget elementor-widget-text-editor\" data-id=\"4a62608\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<div class=\"page\" title=\"Page 2\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Proporcionamos protecci\u00f3n con nuestras patrullas de custodia armada para el resguardo y seguridad de la carga.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ba07d elementor-view-framed elementor-position-left elementor-vertical-align-middle elementor-shape-circle elementor-widget elementor-widget-icon-box\" data-id=\"c3ba07d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-satellite-dish\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tCandado satelital\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPor medio de esto podemos (cliente y nosotros) obtener un control permanente del recorrido de su carga (contenedores, furgones, etc.).\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43aef62\" data-id=\"43aef62\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c85151b elementor-widget elementor-widget-ha-slider happy-addon ha-slider\" data-id=\"c85151b\" data-element_type=\"widget\" data-settings=\"{&quot;animation_speed&quot;:300,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:3000,&quot;loop&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;arrow&quot;}\" data-widget_type=\"ha-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"hajs-slick ha-slick ha-slick--slider\">\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/CUSTODIA-TERRESTRE-470x430-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/custodia_terresetre_4-470x430-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"ha-slick-slide\">\n\t\t\t\t\t<div class=\"ha-slick-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"ha-slick-img\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/guardia-fondo-satforce-seguridad-guardiania-guayaquil-empresaseguridad-quienessomos-satforce-CUSTODIADECARGAS-DRONE-SATELITAL.png\" alt=\"\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t<button type=\"button\" class=\"slick-prev\"><i aria-hidden=\"true\" class=\"fas fa-chevron-left\"><\/i><\/button>\n\t\t\n\t\t\t\t\t<button type=\"button\" class=\"slick-next\"><i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i><\/button>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2b5c55 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"e2b5c55\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e48a1b8\" data-id=\"e48a1b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7bc6da elementor-widget elementor-widget-spacer\" data-id=\"f7bc6da\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43a5793 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"43a5793\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84b2efb\" data-id=\"84b2efb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddce76c elementor-widget elementor-widget-heading\" data-id=\"ddce76c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b6947 elementor-widget elementor-widget-heading\" data-id=\"73b6947\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fluvial<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-615e8c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"615e8c1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5658fd6\" data-id=\"5658fd6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69b6f00 elementor-view-framed elementor-shape-square elementor-widget elementor-widget-icon\" data-id=\"69b6f00\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJ0eXBlIjoidmlkZW8iLCJ2aWRlb1R5cGUiOiJ5b3V0dWJlIiwidXJsIjoiaHR0cHM6XC9cL3d3dy55b3V0dWJlLmNvbVwvZW1iZWRcL29SdDlETzVPQ1AwP2ZlYXR1cmU9b2VtYmVkIn0%3D\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 183.28 91.02\"><defs><style>.a{fill:#8e9090;}<\/style><\/defs><title>maritima-seguridad<\/title><path class=\"a\" d=\"M191.2,83.08a5.56,5.56,0,0,0-5.58-3.37l-31.23,2.62L129.56,56.22A5.55,5.55,0,0,0,125,54.51l-55.83,5a5.56,5.56,0,0,0-4.1,8.67l14,20.5L13.46,94.16a5.56,5.56,0,0,0-3.21,9.71l21,18.54c.8.36,1.56.73,2.3,1.09,3.76,1.82,6.73,3.27,13.34,3.27s9.57-1.44,13.33-3.27a36.52,36.52,0,0,1,18.18-4.38,36.52,36.52,0,0,1,18.18,4.38c3.76,1.82,6.73,3.27,13.34,3.27s9.57-1.44,13.33-3.27a36.52,36.52,0,0,1,18.18-4.38,37.12,37.12,0,0,1,12.2,1.82l13.5-11.77-76.57,4.13h-.25A4.63,4.63,0,0,1,90,104l88.41-4.76,11.29-9.84a5.56,5.56,0,0,0,1.46-6.36Zm-99.37,4.5L79.64,69.71l43.71-3.89,16.83,17.7Zm0,0\" transform=\"translate(-8.36 -54.49)\"><\/path><path class=\"a\" d=\"M141.41,126.77a36.54,36.54,0,0,0-18.18,4.38c-3.76,1.83-6.73,3.27-13.33,3.27s-9.57-1.44-13.34-3.27a36.54,36.54,0,0,0-18.18-4.38,36.52,36.52,0,0,0-18.18,4.38c-3.76,1.83-6.73,3.27-13.33,3.27S37.3,133,33.54,131.15a36.54,36.54,0,0,0-18.18-4.38v11.09c6.6,0,9.58,1.44,13.34,3.27a36.52,36.52,0,0,0,18.18,4.38,36.52,36.52,0,0,0,18.18-4.38c3.76-1.83,6.73-3.27,13.33-3.27s9.57,1.44,13.33,3.27a36.52,36.52,0,0,0,18.18,4.38,36.53,36.53,0,0,0,18.18-4.38c3.76-1.83,6.73-3.27,13.33-3.27s9.57,1.44,13.34,3.27a36.52,36.52,0,0,0,18.18,4.38V134.42c-6.6,0-9.57-1.44-13.34-3.27a36.54,36.54,0,0,0-18.18-4.38Zm0,0\" transform=\"translate(-8.36 -54.49)\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58072bc dce_masking-none elementor-widget elementor-widget-image\" data-id=\"58072bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"433\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador.png\" class=\"attachment-1536x1536 size-1536x1536\" alt=\"\" srcset=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador.png 800w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador-300x162.png 300w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador-768x416.png 768w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador-24x13.png 24w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador-36x19.png 36w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2021\/01\/custodia_fluvial_satforce_seguridad_ecuador-48x26.png 48w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2f9280 elementor-widget elementor-widget-spacer\" data-id=\"e2f9280\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6560b0f elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"6560b0f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bd8788\" data-id=\"7bd8788\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fbf637 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"2fbf637\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed04240 elementor-widget elementor-widget-heading\" data-id=\"ed04240\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CUSTODIA FLUVIAL<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d7795 elementor-widget elementor-widget-text-editor\" data-id=\"26d7795\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Contamos con nuestras propias lanchas para este servicio.\u00a0La tripulaci\u00f3n se conforma de conductores (marineros) y\u00a0custodios, los cuales cuentan con amplia experiencia.\u00a0Adem\u00e1s, usamos nuestras lanchas patrulleras como apoyo\u00a0para los agentes de seguridad terrestres en camaroneras,\u00a0urbanizaciones, diversas instalaciones, etc.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22025d37 elementor-section-content-top elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22025d37\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73cd25a4\" data-id=\"73cd25a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7bbc3cd0 elementor-section-content-top elementor-section-full_width elementor-hidden-tablet elementor-hidden-phone elementor-section-height-default elementor-section-height-default\" data-id=\"7bbc3cd0\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-755734fd\" data-id=\"755734fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3334c985 animated-slow elementor-invisible elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"3334c985\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/satforce.com.ec\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"190\" src=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1.png 190w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1-150x150.png 150w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1-24x24.png 24w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1-36x36.png 36w, https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/09\/cropped-LOGO-SATFORCE-b-1-48x48.png 48w\" sizes=\"(max-width: 34.9rem) calc(100vw - 2rem), (max-width: 53rem) calc(8 * (100vw \/ 12)), (min-width: 53rem) calc(6 * (100vw \/ 12)), 100vw\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7aa37b e-grid-align-left e-grid-align-tablet-right elementor-shape-circle e-grid-align-mobile-center elementor-grid-0 elementor-invisible elementor-widget elementor-widget-social-icons\" data-id=\"7c7aa37b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-animation-shrink elementor-repeater-item-6a089dc\" href=\"https:\/\/www.linkedin.com\/company\/satforceec\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-animation-shrink elementor-repeater-item-c29d3e9\" href=\"https:\/\/www.facebook.com\/Satforce-109028870598968\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-shrink elementor-repeater-item-87d6eb6\" href=\"https:\/\/www.instagram.com\/satforce_ec\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-377b81f5 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"377b81f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-724f1004 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"724f1004\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Satforce<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60547d30 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"60547d30\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>SERVICIOS DE SEGURIDAD PROFESIONAL<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-67df9dd7\" data-id=\"67df9dd7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51cf16a2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"51cf16a2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/g.page\/Satforce?share\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kennedy Norte Mz. 601 villa 3<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+59344001072\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">04-4001072<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:ventas@satforce.com.ec\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ventas@satforce.com.ec<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bbc9306 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bbc9306\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f9589d3\" data-id=\"2f9589d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a9d1c0b elementor-widget elementor-widget-heading\" data-id=\"1a9d1c0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u00a9 SATFORCE 2020 - DERECHOS RESERVADO<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Custodia CUSTODIA Terrestre https:\/\/mostbets.kz\/snaipin up4rabet bangladeshmosbet CUSTODIA TERRESTRE Nuestro servicio de custodia terrestre se realiza a trav\u00e9s de una escolta vehicular. Esta escolta garantiza protecci\u00f3n a los bienes resguardados, apoy\u00e1ndose en servicios especializados como ghostwriter diplomarbeit. Por lo tanto, poseemos una flota de camionetas y el personal humano mejor capacitado del pa\u00eds. Custodia personal Custodia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-264","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v14.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Custodia - SatForce<\/title>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/satforce.com.ec\/index.php\/custodia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Custodia - SatForce\" \/>\n<meta property=\"og:description\" content=\"Custodia CUSTODIA Terrestre https:\/\/mostbets.kz\/snaipin up4rabet bangladeshmosbet CUSTODIA TERRESTRE Nuestro servicio de custodia terrestre se realiza a trav\u00e9s de una escolta vehicular. Esta escolta garantiza protecci\u00f3n a los bienes resguardados, apoy\u00e1ndose en servicios especializados como ghostwriter diplomarbeit. Por lo tanto, poseemos una flota de camionetas y el personal humano mejor capacitado del pa\u00eds. Custodia personal Custodia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/satforce.com.ec\/index.php\/custodia\/\" \/>\n<meta property=\"og:site_name\" content=\"SatForce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Satforce.ec\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T19:35:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/satforce.com.ec\/#website\",\"url\":\"https:\/\/satforce.com.ec\/\",\"name\":\"Satforce\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/satforce.com.ec\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/satforce.com.ec\/index.php\/custodia\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/satforce.com.ec\/wp-content\/uploads\/2020\/10\/satforce_seguridad_custodia_ecuador.png\",\"width\":500,\"height\":971},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/satforce.com.ec\/index.php\/custodia\/#webpage\",\"url\":\"https:\/\/satforce.com.ec\/index.php\/custodia\/\",\"name\":\"Custodia - SatForce\",\"isPartOf\":{\"@id\":\"https:\/\/satforce.com.ec\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/satforce.com.ec\/index.php\/custodia\/#primaryimage\"},\"datePublished\":\"2020-09-25T05:55:33+00:00\",\"dateModified\":\"2025-10-31T19:35:21+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/satforce.com.ec\/index.php\/custodia\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/pages\/264"}],"collection":[{"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/comments?post=264"}],"version-history":[{"count":13,"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/pages\/264\/revisions"}],"predecessor-version":[{"id":26440,"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/pages\/264\/revisions\/26440"}],"wp:attachment":[{"href":"https:\/\/satforce.com.ec\/index.php\/wp-json\/wp\/v2\/media?parent=264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}